{"id":36866,"date":"2025-05-28T10:42:03","date_gmt":"2025-05-28T08:42:03","guid":{"rendered":"https:\/\/mgellogement.fr\/our-residences\/bordeaux\/"},"modified":"2026-06-10T13:08:43","modified_gmt":"2026-06-10T11:08:43","slug":"bordeaux","status":"publish","type":"page","link":"https:\/\/mgellogement.fr\/en\/our-residences\/bordeaux\/","title":{"rendered":"Student housing in Bordeaux"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;80&#8243; bottom_padding=&#8221;80&#8243; top_padding_phone=&#8221;40&#8243; bottom_padding_phone=&#8221;40&#8243; left_padding_phone=&#8221;0&#8243; right_padding_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;-1000&#8243; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column left_padding_desktop=&#8221;20&#8243; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;parallax&#8221; animation_movement_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;4&#8243; column_border_color=&#8221;#ff6b3d&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h1><span style=\"color: #707070;\">Student housing<br \/>\nin Bordeaux<\/span><\/h1>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1749201640893{padding-right: 0px !important;padding-left: 0px !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; left_margin=&#8221;0&#8243; right_margin=&#8221;0&#8243; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2 style=\"font-family: 'Poppins', sans-serif; font-weight: 500; font-size: 18px; color: #d2430e; line-height: 28px; letter-spacing: -0.03em;\"><strong>2 student residences and 127 apartments from 10 to 29 m\u00b2<\/strong><\/h2>\n<p><strong><span style=\"color: #707070;\">A wide choice of student housing in Bordeaux, with included services combining practicality, comfort, and a friendly atmosphere.<\/span><br \/>\n<\/strong>Bordeaux is located in the Nouvelle-Aquitaine region, in the Gironde department. In 2024, it has approximately 261,804 inhabitants. The city hosts nearly 88,000 students. Nearby towns include Le Bouscat (3.4 km), Talence (3.4 km), B\u00e8gles (4.1 km), Floirac (4.2 km), Cenon (4.3 km), M\u00e9rignac (5.2 km), Pessac (5.5 km), Bruges (5.6 km), Lormont (6.5 km), and Villenave-d\u2019Ornon (6.5 km).[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f2f2f2&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;80&#8243; bottom_padding=&#8221;80&#8243; top_padding_phone=&#8221;50&#8243; bottom_padding_phone=&#8221;50&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<div class=\"es-properties js-es-properties js-es-entities-wrap es-properties--hfm--full-width\">\n    \n    <div class=\"es-properties__list\">\n\t    \n<div class=\"es-listings__wrap-inner js-es-listings__wrap-inner js-es-entities__wrap_inner et_smooth_scroll_disabled\">\n    <div class=\"es-listings-filter js-es-listings-filter\">\n            <span class=\"es-title\">Student housing in Bordeaux<\/span>\n    \n            <span class=\"es-total\">\n            2 results        <\/span>\n        \n    <div class=\"es-listings-filter__selects\">\n                                                <div class=\"es-form\">\n                \n                               <div class='js-es-field es-field es-field__sort es-field--select '>\n                                   <label for='es-field-sort'><span class='es-field__label'>Sort by<\/span>\n\t\t\t<select id=\"es-field-sort\" name=\"sort\" class=\"js-es-sort es-field__input\" ><option value=\"lowest_price\"  selected='selected'>Lowest price<\/option><option value=\"highest_price\" >Highest price<\/option><\/select>\n\t\t<\/label>\n                               <\/div>\n                                       <\/div>\n                                                            <ul class=\"js-es-control--layouts es-control es-control--layouts\">\n    <li class=\"es-control__grid\">\n        <a href=\"\/en\/wp-json\/wp\/v2\/pages\/36866?layout=grid-4\" data-layout=\"grid-4\" class=\"js-es-change-layout es-btn es-btn--icon es-btn--gray es-btn--big es-btn--active\">\n            <span class=\"es-icon es-icon_grid\"><\/span>Grid<\/a>\n    <\/li>\n    <li class=\"es-control__list\">\n        <a href=\"\/en\/wp-json\/wp\/v2\/pages\/36866?layout=list\" data-layout=\"list\" class=\"js-es-change-layout es-btn es-btn--icon es-btn--gray es-btn--big \">\n            <span class=\"es-icon es-icon_grid-row\"><\/span>List<\/a>\n    <\/li>\n    <li class=\"es-control__hfm\">\n        <a href=\"\/en\/wp-json\/wp\/v2\/pages\/36866?layout=half_map\" data-layout=\"half_map\" class=\"js-es-change-layout es-btn es-btn--icon es-btn--gray es-btn--big \">\n            <span class=\"es-icon es-icon_marker\"><\/span>Half Map<\/a>\n    <\/li>\n<\/ul>\n                        <\/div>\n<\/div>\n\n\n    <div itemscope itemtype=\"https:\/\/schema.org\/ItemList\" data-entity=\"listings\" class=\"js-es-listings js-es-entities es-listings es-listings--grid-4\" data-layout=\"es-listings--grid-4\" data-hash=\"bGF5b3V0PWdyaWQtNCZwb3N0c19wZXJfcGFnZT00MCZkaXNhYmxlX25hdmJhcj0wJnNob3dfc29ydD0xJnNob3dfdG90YWw9MSZzaG93X3BhZ2VfdGl0bGU9MSZzaG93X2N1cnJlbmNpZXM9JnNob3dfY2F0ZWdvcmllcz0wJnNob3dfbGF5b3V0cz0xJnNvcnQ9bG93ZXN0X3ByaWNlJmxpbWl0PTAmbG9vcF91aWQ9MSZwYWdlX3RpdGxlPVN0dWRlbnQgaG91c2luZyBpbiBCb3JkZWF1eCZpZ25vcmVfc2VhcmNoPTAmZW5hYmxlX3NlYXJjaD0wJnNlYXJjaF90eXBlPXNpbXBsZSZlbmFibGVfYWpheD0xJnZpZXdfYWxsX2xpbmtfbmFtZT1WaWV3IGFsbCZkaXNhYmxlX3BhZ2luYXRpb249MCZ3aXNobGlzdF9jb25maXJtPTAmaGZtX2Z1bGxfd2lkdGg9MSZfaWdub3JlX2Nvb3JkaW5hdGVzPTAmZmllbGRzX2RlbGltaXRlcj0sJnN0cmljdF9hZGRyZXNzPTAmbWFwX3Nob3c9MCZhdXRob3JzPTAmZXNfbGFiZWw9MTcw\">\n                                        <div id=\"post-37056\" class=\"post-37056 properties type-properties status-publish has-post-thumbnail es_location-bruges es_location-france es_location-gironde es_location-nouvelle-aquitaine es_type-t1 es_type-t1-bis es_label-bordeaux es_label-fully-booked es-post-entity\" itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\">\n    <div class=\"js-es-listing es-listing es-listing--37056\" data-post-id=\"37056\" itemprop=\"item\" itemscope itemtype=\"https:\/\/schema.org\/House\">\n        \n<div class=\"es-listing__image\">\n        <ul class=\"es-badges es-badges--rounded\">\n                    <li class=\"es-badge\" style=\"background: #ff7e00;\">\n                <a  href=\"https:\/\/mgellogement.fr\/en\/label\/bordeaux\/\">BORDEAUX<\/a><\/li>\n                    <li class=\"es-badge\" style=\"background: #323232;\">\n                <a  href=\"https:\/\/mgellogement.fr\/en\/label\/fully-booked\/\">FULLY BOOKED<\/a><\/li>\n            <\/ul>\n        <div class=\"es-property__control es-listing--hide-on-list\">\n        \n<ul class=\"js-es-control es-control es-control--property-image\">\n\t\t\t\t<\/ul>    <\/div>\n            <div class=\"es-listing__image__background\" style=\"background-image: url('https:\/\/mgellogement.fr\/wp-content\/uploads\/2025\/06\/Logement-etudiant-Residence-Bordeaux-Terrefort-a-Metz-location-universitaires.jpg')\">\n            <a class=\"es-listings__image__link\"  href=\"https:\/\/mgellogement.fr\/en\/logement-etudiant\/bordeaux-terrefort\/\"><\/a>\n        <\/div>\n    <\/div>\n        <div class=\"es-listing__content\">\n            <div class=\"es-listing__content__inner\">\n                <div class=\"es-listing__content__left\">\n                    <meta itemprop=\"name\" content=\"<span class='titre-en-plus'>Student residence<br><\/span> Bordeaux Terrefort\" \/>\n                    <meta itemprop=\"image\" content=\"https:\/\/mgellogement.fr\/wp-content\/uploads\/2025\/06\/Logement-etudiant-Residence-Bordeaux-Terrefort-a-Metz-location-universitaires-150x150.jpg\" \/>\n                    <h3 class=\"es-listing__title\">\n                        <a href=\"https:\/\/mgellogement.fr\/en\/logement-etudiant\/bordeaux-terrefort\/\"  itemprop=\"url\"><span class='titre-en-plus'>Student residence<br><\/span> Bordeaux Terrefort<\/a><\/h3>                    <div class='es-badges es-listing--hide-on-list'>\n                        <span class=\"es-price\">348\u20ac<\/span><span class=\"es-badge es-badge--normal\">T1 starting from<\/span><\/div>\n                    <div class=\"es-address es-listing--hide-on-grid\">162D Av. Charles de Gaulle, 33520 Bruges<\/div><div class=\"es-listing__meta\"><\/div><div class=\"es-address es-listing--hide-on-list\">162D Av. Charles de Gaulle, 33520 Bruges<\/div>                <\/div>\n                <div class=\"es-listing__content__right es-listing--hide-on-grid\">\n                    <div class=\"es-property__control es-listing--hide-on-grid\">\n                        \n<ul class=\"js-es-control es-control es-control--property-content\">\n\t\t\t\t<\/ul>                    <\/div>\n                    <span class=\"es-price\">348\u20ac<\/span>                    <span class=\"es-badge es-badge--normal\">T1 starting from<\/span>                <\/div>\n            <\/div>\n            <div class=\"es-listing__footer\">\n                    <ul class=\"es-listing__terms\">                    <li><a href=\"https:\/\/mgellogement.fr\/en\/property-type\/t1\/\">T1<\/a><\/li>\n                    <li><a href=\"https:\/\/mgellogement.fr\/en\/property-type\/t1-bis\/\">T1 bis<\/a><\/li>\n            <\/ul>\n                            <\/div>\n\n                    <\/div>\n    <\/div>\n    <\/div>\n                                <div id=\"post-37065\" class=\"post-37065 properties type-properties status-publish has-post-thumbnail es_location-bordeaux es_location-france es_location-gironde es_location-nouvelle-aquitaine es_type-t1 es_label-bordeaux es-post-entity\" itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\">\n    <div class=\"js-es-listing es-listing es-listing--37065\" data-post-id=\"37065\" itemprop=\"item\" itemscope itemtype=\"https:\/\/schema.org\/House\">\n        \n<div class=\"es-listing__image\">\n        <ul class=\"es-badges es-badges--rounded\">\n                    <li class=\"es-badge\" style=\"background: #ff7e00;\">\n                <a  href=\"https:\/\/mgellogement.fr\/en\/label\/bordeaux\/\">BORDEAUX<\/a><\/li>\n            <\/ul>\n        <div class=\"es-property__control es-listing--hide-on-list\">\n        \n<ul class=\"js-es-control es-control es-control--property-image\">\n\t\t\t\t<\/ul>    <\/div>\n            <div class=\"es-listing__image__background\" style=\"background-image: url('https:\/\/mgellogement.fr\/wp-content\/uploads\/2025\/06\/Bordeaux2-2-1024x605.avif')\">\n            <a class=\"es-listings__image__link\"  href=\"https:\/\/mgellogement.fr\/en\/logement-etudiant\/bordeaux\/\"><\/a>\n        <\/div>\n    <\/div>\n        <div class=\"es-listing__content\">\n            <div class=\"es-listing__content__inner\">\n                <div class=\"es-listing__content__left\">\n                    <meta itemprop=\"name\" content=\"<span class='titre-en-plus'>Student residence<br><\/span> Bordeaux\" \/>\n                    <meta itemprop=\"image\" content=\"https:\/\/mgellogement.fr\/wp-content\/uploads\/2025\/06\/Bordeaux2-2-150x150.avif\" \/>\n                    <h3 class=\"es-listing__title\">\n                        <a href=\"https:\/\/mgellogement.fr\/en\/logement-etudiant\/bordeaux\/\"  itemprop=\"url\"><span class='titre-en-plus'>Student residence<br><\/span> Bordeaux<\/a><\/h3>                    <div class='es-badges es-listing--hide-on-list'>\n                        <span class=\"es-price\">655\u20ac<\/span><span class=\"es-badge es-badge--normal\">Rent starting at<\/span><\/div>\n                    <div class=\"es-address es-listing--hide-on-grid\">51 Rue Lacorn\u00e9e, 33000 Bordeaux<\/div><div class=\"es-listing__meta\"><\/div><div class=\"es-address es-listing--hide-on-list\">51 Rue Lacorn\u00e9e, 33000 Bordeaux<\/div>                <\/div>\n                <div class=\"es-listing__content__right es-listing--hide-on-grid\">\n                    <div class=\"es-property__control es-listing--hide-on-grid\">\n                        \n<ul class=\"js-es-control es-control es-control--property-content\">\n\t\t\t\t<\/ul>                    <\/div>\n                    <span class=\"es-price\">655\u20ac<\/span>                    <span class=\"es-badge es-badge--normal\">Rent starting at<\/span>                <\/div>\n            <\/div>\n            <div class=\"es-listing__footer\">\n                    <ul class=\"es-listing__terms\">                    <li><a href=\"https:\/\/mgellogement.fr\/en\/property-type\/t1\/\">T1<\/a><\/li>\n            <\/ul>\n                            <\/div>\n\n                    <\/div>\n    <\/div>\n    <\/div>\n                        <\/div>\n\t    <\/div>\n    <\/div>\n    <div class=\"js-es-properties__map es-properties__map \">\n\t        <div id=\"properties-map-6a97f737698a6\" class=\"js-es-map es-map\" data-listings=\"{&quot;37056&quot;:{&quot;lat&quot;:&quot;44.8864769&quot;,&quot;lng&quot;:&quot;-0.6111188&quot;,&quot;post_id&quot;:37056,&quot;price&quot;:&quot;348\\u20ac&quot;},&quot;37065&quot;:{&quot;lat&quot;:&quot;44.8332253&quot;,&quot;lng&quot;:&quot;-0.5821476&quot;,&quot;post_id&quot;:37065,&quot;price&quot;:&quot;655\\u20ac&quot;}}\"><\/div>\n    <\/div>\n<\/div>\n\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<div class=\"js-es-properties es-property-map\" style=\"height:300px; width:100%;\">\n    <div class=\"js-es-properties__map es-properties__map es-properties__map--visible\">\n            <div id=\"properties-map-6a97f7376b69f\" class=\"js-es-map es-map\" data-listings=\"{&quot;37056&quot;:{&quot;lat&quot;:&quot;44.8864769&quot;,&quot;lng&quot;:&quot;-0.6111188&quot;,&quot;post_id&quot;:37056,&quot;price&quot;:&quot;348\\u20ac&quot;},&quot;37065&quot;:{&quot;lat&quot;:&quot;44.8332253&quot;,&quot;lng&quot;:&quot;-0.5821476&quot;,&quot;post_id&quot;:37065,&quot;price&quot;:&quot;655\\u20ac&quot;}}\"><\/div>\n    <\/div>\n    <div data-entity=\"listings\" class=\"js-es-listings js-es-entities es-hidden\" data-hash=\"bGF5b3V0PWhhbGZfbWFwJnBvc3RzX3Blcl9wYWdlPTQwJmRpc2FibGVfbmF2YmFyPTAmc2hvd19zb3J0PTEmc2hvd190b3RhbD0xJnNob3dfcGFnZV90aXRsZT0xJnNob3dfY3VycmVuY2llcz0mc2hvd19jYXRlZ29yaWVzPTAmc2hvd19sYXlvdXRzPTEmc29ydD1sb3dlc3RfcHJpY2UmbGltaXQ9MCZsb29wX3VpZD0yJnBhZ2VfdGl0bGU9PHNwYW4gY2xhc3M9J3RpdHJlLWVuLXBsdXMnPlN0dWRlbnQgcmVzaWRlbmNlPGJyPjwvc3Bhbj4gQm9yZGVhdXgmaWdub3JlX3NlYXJjaD0wJmVuYWJsZV9zZWFyY2g9MCZzZWFyY2hfdHlwZT1zaW1wbGUmZW5hYmxlX2FqYXg9MSZ2aWV3X2FsbF9saW5rX25hbWU9VmlldyBhbGwmZGlzYWJsZV9wYWdpbmF0aW9uPTAmd2lzaGxpc3RfY29uZmlybT0wJmhmbV9mdWxsX3dpZHRoPTAmX2FqYXhfbW9kZT0wJl9pZ25vcmVfY29vcmRpbmF0ZXM9MCZmaWVsZHNfZGVsaW1pdGVyPSwmc3RyaWN0X2FkZHJlc3M9MCZtYXBfc2hvdz0wJmF1dGhvcnM9MCZ3aWR0aD0xMDAlJmhlaWdodD0zMDBweCZlc19sYWJlbD0xNzA=\"><\/div>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;40&#8243; bottom_padding=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2 class=\"title\"><span style=\"color: #d2430e;\">Bordeaux in 5 points<br \/>\n<\/span><\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;30&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;1&#8243; column_border_color=&#8221;#d1d1d1&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1748421877515{padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221;]<span style=\"color: #000000;\"><strong>Historical Heritage<\/strong><\/span><\/p>\n<ul>\n<li>UNESCO historic center with the Place de la Bourse<\/li>\n<li>Saint-Andr\u00e9 Cathedral<\/li>\n<li>Perfectly preserved 18th-century districts along the Garonne River<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;1&#8243; column_border_color=&#8221;#d1d1d1&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1748421927482{padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221;]<strong>Nature and Relaxation<\/strong><\/p>\n<ul>\n<li class=\"whitespace-normal break-words\">Public gardens in the city center<\/li>\n<li class=\"whitespace-normal break-words\">Developed banks of the Garonne<\/li>\n<li class=\"whitespace-normal break-words\">Exceptional proximity to the Atlantic Ocean and the Arcachon Bay.<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;1&#8243; column_border_color=&#8221;#d1d1d1&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1748421972847{padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221;]<strong>Culture<\/strong><\/p>\n<ul class=\"-mt-1 [li&gt;&amp;]:mt-2 list-disc space-y-2 pl-8\">\n<li class=\"whitespace-normal break-words\">High-quality museums (Cit\u00e9 du Vin, CAPC)<\/li>\n<li class=\"whitespace-normal break-words\">National Opera<\/li>\n<li class=\"whitespace-normal break-words\">Renowned festivals and a dynamic art scene with numerous galleries<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;1&#8243; column_border_color=&#8221;#d1d1d1&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1748422012195{padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221;]<strong>Outings and Entertainment<\/strong><\/p>\n<ul class=\"-mt-1 [li&gt;&amp;]:mt-2 list-disc space-y-2 pl-8\">\n<li>Lively Saint-Pierre district<\/li>\n<li class=\"whitespace-normal break-words\">Sainte-Catherine shopping street<\/li>\n<li class=\"whitespace-normal break-words\">Nighttime quays and authentic markets like the Capucins market<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;1&#8243; column_border_color=&#8221;#d1d1d1&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1748422061494{padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221;]<strong>Student Life<\/strong><\/p>\n<ul class=\"-mt-1 [li&gt;&amp;]:mt-2 list-disc space-y-2 pl-8\">\n<li>More than 90,000 students<\/li>\n<li>Renowned university<\/li>\n<li>Central campus<\/li>\n<li>Numerous price advantages for students.<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f2f2f2&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;80&#8243; bottom_padding=&#8221;80&#8243; top_padding_phone=&#8221;60&#8243; bottom_padding_phone=&#8221;50&#8243; left_padding_phone=&#8221;0&#8243; right_padding_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;-1000&#8243; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column left_padding_desktop=&#8221;20&#8243; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;4&#8243; column_border_color=&#8221;#ff6b3d&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2 class=\"title\"><span style=\"color: #707070;\">Student Residences<br \/>\nwith \u00c0 La Carte Services<\/span><\/h2>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1749201640893{padding-right: 0px !important;padding-left: 0px !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; left_margin=&#8221;0&#8243; right_margin=&#8221;0&#8243; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<span style=\"color: #707070;\"><strong>Since its creation, MGEL Logement has supported young people and is committed to providing them with an optimal quality of life.<\/strong><\/span><br \/>\nServices are available to residents to encourage social moments: sauna, coworking space, gym, lounge, etc. These services are not included in the rent and vary depending on the student residence. All our student apartments are eligible for housing assistance.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;80&#8243; bottom_padding=&#8221;80&#8243; top_padding_phone=&#8221;50&#8243; left_padding_phone=&#8221;0&#8243; right_padding_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; border_left_desktop=&#8221;4&#8243; column_border_color=&#8221;#ff6b3d&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1769436998038{padding-left: 20px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<h2 class=\"title\"><span style=\"color: #707070;\">How do I book my student apartment?<\/span><\/h2>\n<p><span style=\"color: #707070;\"><br \/>\n100% digital booking in <strong>3 steps<\/strong><\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin_phone=&#8221;20&#8243; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; left_padding_tablet=&#8221;100&#8243; right_padding_tablet=&#8221;100&#8243; left_padding_phone=&#8221;0&#8243; right_padding_phone=&#8221;0&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; class=&#8221;bloc-home-choisir&#8221;][vc_column_inner left_padding_desktop=&#8221;20&#8243; right_padding_desktop=&#8221;20&#8243; constrain_group_2=&#8221;yes&#8221; left_margin_phone=&#8221;20&#8243; right_margin_phone=&#8221;20&#8243; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;10px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;2px&#8221; column_border_color=&#8221;#ffffff&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;][divider line_type=&#8221;no-line&#8221; custom_height=&#8221;20&#8243;][\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1748251719948{margin-top: -10px !important;margin-bottom: 5px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #d2430e;\">Step<\/span><\/p>\n[\/vc_column_text][image_with_animation image_url=&#8221;36180&#8243; image_size=&#8221;full&#8221; max_width=&#8221;75%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; margin_left=&#8221;40%&#8221; margin_right=&#8221;40%&#8221; margin_bottom=&#8221;10&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3 style=\"text-align: center;\">I choose my residence<\/h3>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\"><small><span data-teams=\"true\">I select the student residence that suits me and specify the type of accommodation I want by filling out the online pre-booking form<\/span><\/small><\/p>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;][divider line_type=&#8221;no-line&#8221; custom_height=&#8221;20&#8243;][\/vc_column_text][\/vc_column_inner][vc_column_inner left_padding_desktop=&#8221;20&#8243; right_padding_desktop=&#8221;20&#8243; left_margin_phone=&#8221;20&#8243; right_margin_phone=&#8221;20&#8243; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;10px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;2px&#8221; column_border_color=&#8221;#ffffff&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;][divider line_type=&#8221;no-line&#8221; custom_height=&#8221;20&#8243;][\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1748251719948{margin-top: -10px !important;margin-bottom: 5px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #d2430e;\">Step<\/span><\/p>\n[\/vc_column_text][image_with_animation image_url=&#8221;36179&#8243; image_size=&#8221;full&#8221; max_width=&#8221;75%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; margin_left=&#8221;40%&#8221; margin_right=&#8221;40%&#8221; margin_bottom=&#8221;10&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3 style=\"text-align: center;\">I confirm my request<\/h3>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\"><small><span data-teams=\"true\">I upload the documents required for my tenant application online to finalize my request and secure my housing<\/span><br \/>\n<\/small><\/p>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;][divider line_type=&#8221;no-line&#8221; custom_height=&#8221;20&#8243;][\/vc_column_text][\/vc_column_inner][vc_column_inner left_padding_desktop=&#8221;20&#8243; right_padding_desktop=&#8221;20&#8243; left_margin_phone=&#8221;20&#8243; right_margin_phone=&#8221;20&#8243; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;10px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;2px&#8221; column_border_color=&#8221;#ffffff&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;][divider line_type=&#8221;no-line&#8221; custom_height=&#8221;20&#8243;][\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1748251719948{margin-top: -10px !important;margin-bottom: 5px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #d2430e;\">Step<\/span><\/p>\n[\/vc_column_text][image_with_animation image_url=&#8221;36178&#8243; image_size=&#8221;full&#8221; max_width=&#8221;75%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; margin_left=&#8221;40%&#8221; margin_right=&#8221;40%&#8221; margin_bottom=&#8221;10&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3 style=\"text-align: center;\">I receive a confirmation<\/h3>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\"><small><span data-teams=\"true\">I receive a confirmation email summarizing my request. Now just wait while our teams process your application <\/span><\/small><\/p>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;][divider line_type=&#8221;no-line&#8221; custom_height=&#8221;20&#8243;][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;0&#8243; bottom_padding=&#8221;40&#8243; bottom_padding_phone=&#8221;0&#8243; left_padding_phone=&#8221;0&#8243; right_padding_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;-1000&#8243; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column left_padding_desktop=&#8221;0&#8243; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#ff6b3d&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][carousel script=&#8221;carouFredSel&#8221; easing=&#8221;linear&#8221; autorotate=&#8221;true&#8221; autorotate_type=&#8221;ticker&#8221; ticker_speed=&#8221;slow&#8221; ticker_direction=&#8221;default&#8221;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; title=&#8221;\u00c9l\u00e9ment&#8221; id=&#8221;1781089677390-0&#8243; tab_id=&#8221;1781089677391-9&#8243;][image_with_animation image_url=&#8221;32632&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1781089677450-3&#8243; tab_id=&#8221;1781089677451-9&#8243; title=&#8221;\u00c9l\u00e9ment&#8221;][image_with_animation image_url=&#8221;33006&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1781089677473-7&#8243; tab_id=&#8221;1781089677473-4&#8243; title=&#8221;\u00c9l\u00e9ment&#8221;][image_with_animation image_url=&#8221;33008&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1781089677499-7&#8243; tab_id=&#8221;1781089677499-2&#8243; title=&#8221;\u00c9l\u00e9ment&#8221;][image_with_animation image_url=&#8221;33233&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; title=&#8221;\u00c9l\u00e9ment&#8221; id=&#8221;1781089677537-0&#8243; tab_id=&#8221;1781089677537-10&#8243;][image_with_animation image_url=&#8221;33405&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/item][\/carousel][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#FFFFFF&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;37&#8243; left_padding_desktop=&#8221;70&#8243; right_padding_desktop=&#8221;70&#8243; bottom_padding_tablet=&#8221;0&#8243; top_padding_phone=&#8221;35&#8243; bottom_padding_phone=&#8221;0&#8243; left_padding_phone=&#8221;0&#8243; right_padding_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h4><span style=\"color: #707070;\"><strong>A question about our student residences?<\/strong><\/span><\/h4>\n[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1747050602493{margin-top: -25px !important;}&#8221; text_direction=&#8221;default&#8221;]<span style=\"color: #333333;\">Fill out the form, and our team will get back to you as soon as possible<\/span>[\/vc_column_text][nectar_btn size=&#8221;jumbo&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; color_override=&#8221;#d2430e&#8221; solid_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;none&#8221; text=&#8221;Get in touch&#8221; url=&#8221;https:\/\/espace.mgellogement.fr\/en\/contact\/&#8221; css_animation=&#8221;none&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221;...","protected":false},"author":5,"featured_media":0,"parent":36825,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-36866","page","type-page","status-publish"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"The Bordeaux student residence is a house offering 11 rooms with floor areas ranging from 10.79 to 13.68 m\u00b2\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/mgellogement.fr\/en\/logement-etudiant\/bordeaux\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MGEL Logement - R\u00e9sidences \u00e9tudiantes en France\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Student residence Bordeaux - MGEL Logement\" \/>\n\t\t<meta property=\"og:description\" content=\"The Bordeaux student residence is a house offering 11 rooms with floor areas ranging from 10.79 to 13.68 m\u00b2\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/mgellogement.fr\/en\/logement-etudiant\/bordeaux\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/mgellogement.fr\/wp-content\/uploads\/2026\/02\/Residences-etudiantes-MGEL-Logement-logements-etudiants-en-France.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/mgellogement.fr\/wp-content\/uploads\/2026\/02\/Residences-etudiantes-MGEL-Logement-logements-etudiants-en-France.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-06-25T13:59:54+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-09T14:44:14+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Student residence Bordeaux - MGEL Logement\" \/>\n\t\t<meta name=\"twitter:description\" content=\"The Bordeaux student residence is a house offering 11 rooms with floor areas ranging from 10.79 to 13.68 m\u00b2\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/mgellogement.fr\/wp-content\/uploads\/2026\/02\/Residences-etudiantes-MGEL-Logement-logements-etudiants-en-France.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Student residence Bordeaux - MGEL Logement","description":"The Bordeaux student residence is a house offering 11 rooms with floor areas ranging from 10.79 to 13.68 m\u00b2","canonical_url":"https:\/\/mgellogement.fr\/en\/logement-etudiant\/bordeaux\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[]},"og:locale":"en_US","og:site_name":"MGEL Logement - R\u00e9sidences \u00e9tudiantes en France","og:type":"article","og:title":"Student residence Bordeaux - MGEL Logement","og:description":"The Bordeaux student residence is a house offering 11 rooms with floor areas ranging from 10.79 to 13.68 m\u00b2","og:url":"https:\/\/mgellogement.fr\/en\/logement-etudiant\/bordeaux\/","og:image":"https:\/\/mgellogement.fr\/wp-content\/uploads\/2026\/02\/Residences-etudiantes-MGEL-Logement-logements-etudiants-en-France.jpg","og:image:secure_url":"https:\/\/mgellogement.fr\/wp-content\/uploads\/2026\/02\/Residences-etudiantes-MGEL-Logement-logements-etudiants-en-France.jpg","og:image:width":1200,"og:image:height":630,"article:published_time":"2025-06-25T13:59:54+00:00","article:modified_time":"2026-06-09T14:44:14+00:00","twitter:card":"summary_large_image","twitter:title":"Student residence Bordeaux - MGEL Logement","twitter:description":"The Bordeaux student residence is a house offering 11 rooms with floor areas ranging from 10.79 to 13.68 m\u00b2","twitter:image":"https:\/\/mgellogement.fr\/wp-content\/uploads\/2026\/02\/Residences-etudiantes-MGEL-Logement-logements-etudiants-en-France.jpg"},"aioseo_meta_data":{"post_id":"36866","title":null,"description":"2 student residences and 127 apartments from 10 to 29 m\u00b2","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":"#post_title #separator_sa #site_title","og_description":"2 student residences and 127 apartments from 10 to 29 m\u00b2","og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-02-26 09:04:18","updated":"2026-06-10 11:39:31","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mgellogement.fr\/en\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mgellogement.fr\/en\/our-residences\/\" title=\"Our residences\">Our residences<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tStudent housing in Bordeaux\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/mgellogement.fr\/en\/"},{"label":"Our residences","link":"https:\/\/mgellogement.fr\/en\/our-residences\/"},{"label":"Student housing in Bordeaux","link":"https:\/\/mgellogement.fr\/en\/our-residences\/bordeaux\/"}],"_links":{"self":[{"href":"https:\/\/mgellogement.fr\/en\/wp-json\/wp\/v2\/pages\/36866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mgellogement.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mgellogement.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mgellogement.fr\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mgellogement.fr\/en\/wp-json\/wp\/v2\/comments?post=36866"}],"version-history":[{"count":2,"href":"https:\/\/mgellogement.fr\/en\/wp-json\/wp\/v2\/pages\/36866\/revisions"}],"predecessor-version":[{"id":39133,"href":"https:\/\/mgellogement.fr\/en\/wp-json\/wp\/v2\/pages\/36866\/revisions\/39133"}],"up":[{"embeddable":true,"href":"https:\/\/mgellogement.fr\/en\/wp-json\/wp\/v2\/pages\/36825"}],"wp:attachment":[{"href":"https:\/\/mgellogement.fr\/en\/wp-json\/wp\/v2\/media?parent=36866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}